{"id":2758,"date":"2021-11-04T19:57:45","date_gmt":"2021-11-04T18:57:45","guid":{"rendered":"https:\/\/www.tsg-leutkirch.de\/handball\/?p=2758"},"modified":"2021-11-04T20:01:26","modified_gmt":"2021-11-04T19:01:26","slug":"leutkircher-a-jugend-holt-sieg","status":"publish","type":"post","link":"https:\/\/www.tsg-leutkirch.de\/handball\/2021\/11\/04\/leutkircher-a-jugend-holt-sieg\/","title":{"rendered":"Leutkircher A-Jugend holt Sieg"},"content":{"rendered":"<p>Am 16.10 spielte die m\u00e4nnliche A-Jugend von Leutkirch gegen den TV Isny. Die beiden Trainer Christian Volz und Sebastian Herberg bereiteten die Spieler schon lange auf dieses Spiel vor, sodass die Jungs voller Motivation und mit dem Drang das Spiel gegen den Rivalen zu gewinnen, in das Spiel hinein gingen.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-2676 alignright\" src=\"https:\/\/www.tsg-leutkirch.de\/handball\/wp-content\/uploads\/sites\/24\/2021\/10\/0131_mA_2021_10_16-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.tsg-leutkirch.de\/handball\/wp-content\/uploads\/sites\/24\/2021\/10\/0131_mA_2021_10_16-300x200.jpg 300w, https:\/\/www.tsg-leutkirch.de\/handball\/wp-content\/uploads\/sites\/24\/2021\/10\/0131_mA_2021_10_16-1024x682.jpg 1024w, https:\/\/www.tsg-leutkirch.de\/handball\/wp-content\/uploads\/sites\/24\/2021\/10\/0131_mA_2021_10_16-768x512.jpg 768w, https:\/\/www.tsg-leutkirch.de\/handball\/wp-content\/uploads\/sites\/24\/2021\/10\/0131_mA_2021_10_16-1536x1024.jpg 1536w, https:\/\/www.tsg-leutkirch.de\/handball\/wp-content\/uploads\/sites\/24\/2021\/10\/0131_mA_2021_10_16.jpg 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Die Leutkircher Jungs traten mit 11 Spieler an, mit Hilfe vier B-Jugend Spieler. Isny hingegen war nur mit 7 Spielern vertreten. Schon am Anfang des Spieles gelang es den Leutkirchern einen Vorteil gegen\u00fcber den Isnyern aufzubauen. Durch gute Angriffe und mehreren sieben Metern, schaffte es die Mannschaft einen Vorsprung aufzubauen. Auch in der Abwehr lief es bei den Leutkirchern sehr gut und so konnten sie auch mit Hilfe des Torwartes viele Tore verhindern. Zum Ende der ersten Halbzeit konnten die Isnyer aber wieder ein wenig aufholen, durch Fehlp\u00e4sse im Angriff und L\u00fccken in der Verteidigung der Leutkircher. So kam es zu einem Halbzeitstand von 12:8 f\u00fcr die Leutkircher.<\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-2678 alignright\" src=\"https:\/\/www.tsg-leutkirch.de\/handball\/wp-content\/uploads\/sites\/24\/2021\/10\/0133_mA_2021_10_16-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.tsg-leutkirch.de\/handball\/wp-content\/uploads\/sites\/24\/2021\/10\/0133_mA_2021_10_16-300x200.jpg 300w, https:\/\/www.tsg-leutkirch.de\/handball\/wp-content\/uploads\/sites\/24\/2021\/10\/0133_mA_2021_10_16-1024x682.jpg 1024w, https:\/\/www.tsg-leutkirch.de\/handball\/wp-content\/uploads\/sites\/24\/2021\/10\/0133_mA_2021_10_16-768x512.jpg 768w, https:\/\/www.tsg-leutkirch.de\/handball\/wp-content\/uploads\/sites\/24\/2021\/10\/0133_mA_2021_10_16-1536x1024.jpg 1536w, https:\/\/www.tsg-leutkirch.de\/handball\/wp-content\/uploads\/sites\/24\/2021\/10\/0133_mA_2021_10_16.jpg 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Nach einer kurzen Besprechung mit den Trainern kamen die Leutkircher wieder erholt auf das Spielfeld zur\u00fcck. Am Anfang der zweiten Halbzeit ging es sehr ausgeglichen los, beide Mannschaften konnten Tore erzielen. Im sp\u00e4teren Verlauf aber setzten sich die Leutkircher Jungs immer weiter, durch gutes Passspiel und auch sauber gesetzte W\u00fcrfe durch. Am Ende der zweiten Halbzeit merkte man, wie den Isnyer, die keinen Auswechselspieler hatten, die Puste ausging. Dies nutzen die Leutkircher und erreichten zum Ende des Spiels einen Spielstand von 30:20.<\/p>\n<p>Es spielten: Daniel Schlein (TW), Lukas H\u00f6sch(TW), Jonas Maurer(4), Julian Scheich(5), Simon Burger(5), Benjamin Eisele(1), Lars Trieloff(8), Moritz Janusch(0), Paulo Moreira(0), Ilia Solhjou(2), Alexander Kurtz(5)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 16.10 spielte die m\u00e4nnliche A-Jugend von Leutkirch gegen den TV Isny. Die beiden Trainer Christian Volz und Sebastian Herberg bereiteten die Spieler schon lange auf dieses Spiel vor, sodass die Jungs voller Motivation und mit dem Drang das Spiel gegen den Rivalen zu gewinnen, in das Spiel hinein gingen. Die Leutkircher Jungs traten mit [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2669,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1,9],"tags":[],"class_list":["post-2758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-maennliche-a-jugend"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/posts\/2758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/comments?post=2758"}],"version-history":[{"count":5,"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/posts\/2758\/revisions"}],"predecessor-version":[{"id":2763,"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/posts\/2758\/revisions\/2763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/media\/2669"}],"wp:attachment":[{"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/media?parent=2758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/categories?post=2758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/tags?post=2758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}