{"id":5149,"date":"2023-10-17T18:18:51","date_gmt":"2023-10-17T16:18:51","guid":{"rendered":"https:\/\/www.tsg-leutkirch.de\/handball\/?p=5149"},"modified":"2023-10-17T18:18:51","modified_gmt":"2023-10-17T16:18:51","slug":"start-in-die-saison-ist-gelungen","status":"publish","type":"post","link":"https:\/\/www.tsg-leutkirch.de\/handball\/2023\/10\/17\/start-in-die-saison-ist-gelungen\/","title":{"rendered":"Start in die Saison ist gelungen"},"content":{"rendered":"<p>Nachdem leider der HC Vogt seine Mannschaft kurz vor Saisonbeginn zur\u00fcckziehen musste und somit das angek\u00fcndigte Spiel entfiel, fand unser Saisonstart dann bei der JSG Bodensee in Langenargen statt. Mit gro\u00dfer Vorfreude und einiges an Nervosit\u00e4t gestaltete sich die Abfahrt direkt mit einem Autoausfall (kleine Kuriosit\u00e4t am Rande), der gl\u00fccklicherweise schnell durch ein Fahrzeugtausch behoben werden konnte.<\/p>\n<p>In der Halle angekommen erwartete die C-Jugend Jungs gleich die n\u00e4chste H\u00fcrde. Uns erwartete das erste Spiel mit Harz am Ball. Ohne Erfahrung mit dem Haftmittel ist es meist schwierig, die P\u00e4sse und W\u00fcrfe ordentlich anzubringen, da sich der Ball erst mit Verz\u00f6gerung von der Hand l\u00f6st und tendenziell immer zu tief an seinem Bestimmungsort ankommt. Zum Einspielen konnten wir uns zum Gl\u00fcck einen Ball der JSG ausleihen und uns ein wenig eingew\u00f6hnen. Und die Jungs kamen \u00fcberraschend gut klar damit.<\/p>\n<p>Bis zur 21. Minute dominierte die TSG das Spielgeschehen und konnte trotz einiger guter Paraden des JSG Keepers und einigen Fehlw\u00fcrfen auf 1:7 davon ziehen, entscheidend hierf\u00fcr war eine sich sehr gut verschiebende Abwehr, die extrem wenig M\u00f6glichkeiten zugelassen hat, und wenn dann mal ein Wurf durchkam stand da noch Kilian im Tor im Weg. In den letzten Minuten der ersten H\u00e4lfte, begleitet von vielen Wechseln, schlichen sich dann zu viele Fehler ein und die F\u00fchrung zur Halbzeit schrumpfte auf 4 Tore (4:8). In der Kabine mussten nach dieser Halbzeit nur kleine Dinge angesprochen werden, vor allem sollte die Konzentration weiter hochgehalten werden.<\/p>\n<p>Die jetzt noch etwas offensivere Abwehr der Hausherren war aber eher eine Einladung als ein Hindernis, auch wenn zu oft mal wieder die letzten P\u00e4sse nicht ihr Ziel erreichten. Aber der Ergebnisverlauf war immer noch zufriedenstellend. \u00dcber 7:15 und 12:20 erreichte man zum Schlusspfiff ein Endergebnis von 15:23. Standortbestimmung unter Wettkampfbedingungen gelungen. Fazit des Spiels: wir haben nat\u00fcrlich noch ein paar Baustellen aber die C-Jugend ist weiter wie erwartet nach der holprigen Vorbereitung.<\/p>\n<p>Gespielt haben:<\/p>\n<p>Julian M. (1); Hannes L.; Timo S.; Robin S. (1); Jakob B. (4); Johannes H. (6); Levin H. (10); Filipe R.; Matthias G. (1); Kilian M. (TW)<\/p>\n<p>Duell mit Laupheim<\/p>\n<p>Erneut an einem Sonntagnachmittag durften wir die Fahrt antreten, dieses Mal mit dem Ziel Laupheim. Laupheims zweite C-Jugend konnte bereits Isny schlagen und verbuchte somit ebenso wie wir bisher einen Sieg. Ebenso ist Laupheim meist technisch gut ausgebildet und lassen die Spieler im Rahmen der erlaubten Wechsel gerne durch die Mannschaften rotieren. Dahingehend wurde die Mannschaft eingestellt und vorgewarnt. Die normale Routine des Warmmachens musste auch dieses Mal erg\u00e4nzt werden, um die Harzgew\u00f6hnung, nachdem aber in der vergangenen Woche das Spielen mit dem Haftmittel schon gut funktioniert hat, sollte es auch gegen Laupheim gut gehen.<\/p>\n<p>Schnell wurde klar, dass von den Gastgebern nicht allzu viel Gegenwehr zu erwarten war, auch die sehr offensive Abwehr konnte unseren R\u00fcckraum nicht wirklich beeindrucken. Die R\u00e4ume im R\u00fccken der Verteidigung wurden immer wieder durch die Au\u00dfenspieler angelaufen und die Abwehr so in Bewegung gebracht und R\u00e4ume ge\u00f6ffnet. Zum Halbzeitpfiff lagen unsere C-Jugend Jungs dann auch schon 4:9 in F\u00fchrung. Die klare F\u00fchrung bot Trainer Christoph H\u00f6sch schon fr\u00fch die Chance, auch die unerfahrenen Spieler von der Bank ins Rennen zu schicken und sie machten alle einen super Job. Auch konnten wir eine andere Abwehrvariante in der zweiten H\u00e4lfte spielen. Die neue 4:2-Variante passte gut auf die st\u00e4rkeren Halbspieler der Laupheimer, deren Bewegungsradius wir damit sehr einschr\u00e4nken konnten. Letzten Endes steuerten wir erneut auf einen ungef\u00e4hrdeten Sieg hin und das Endergebnis von 12:22 war hoch verdient. Trainer Christoph war nat\u00fcrlich mit dem Endergebnis zufrieden, dennoch wurden nach seiner Meinung noch zu viele klare Abschl\u00fcsse sehr leichtfertig vergeben und ebenso oft wurde erneut der finale Pass ohne die letzte Konsequenz und Cleverness gespielt.<\/p>\n<p>Gespielt haben: (laut Spielprotokoll)<\/p>\n<p>Julian M., Vinz W.; Timo S. (2), Robin S. (1), Jakob B. (1), Johannes H. (7), Levin H. (9), Felipe R., Matthias G. (2), Kilian M. (TW),<\/p>\n<p>&nbsp;<\/p>\n<p>Derby in eigener Halle<\/p>\n<p>Nach den zwei erfolgreichen Ausw\u00e4rtspartien erwartet die C-m\u00e4nnlich am Samstag den 21. den TV Isny das Derby der Saison. Die Spiele gegen die Nachbarn aus Isny sind immer von einer besonderen Brisanz begleitet. Aber im Vorfeld sprechen die nackten Zahlen f\u00fcr unsere Leutkircher Jungs, zwei klare Siege gegen eine Niederlage und ein Unentschieden der G\u00e4ste aus Isny heben die Erwartungen. Laut dem Trainergespann sollen sich die Jungs der C-Jugend auf das eigene Spiel konzentrieren und dieses auch auf die Spielfl\u00e4che zu bringen. Die Vorfreude ist gro\u00df, die Jungs sind hei\u00df und wollen die Serie der Siege am Leben halten. Sofern nicht noch irgendwelche \u00dcberraschungen kommen, werden wir auf den kompletten Kader zur\u00fcckgreifen.<\/p>\n<p>Wir w\u00fcnschen Ihnen beste Unterhaltung beim Spiel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachdem leider der HC Vogt seine Mannschaft kurz vor Saisonbeginn zur\u00fcckziehen musste und somit das angek\u00fcndigte Spiel entfiel, fand unser Saisonstart dann bei der JSG Bodensee in Langenargen statt. Mit gro\u00dfer Vorfreude und einiges an Nervosit\u00e4t gestaltete sich die Abfahrt direkt mit einem Autoausfall (kleine Kuriosit\u00e4t am Rande), der gl\u00fccklicherweise schnell durch ein Fahrzeugtausch behoben [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1,11],"tags":[],"class_list":["post-5149","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-maennliche-c-jugend"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/posts\/5149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/comments?post=5149"}],"version-history":[{"count":1,"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/posts\/5149\/revisions"}],"predecessor-version":[{"id":5150,"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/posts\/5149\/revisions\/5150"}],"wp:attachment":[{"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/media?parent=5149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/categories?post=5149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tsg-leutkirch.de\/handball\/wp-json\/wp\/v2\/tags?post=5149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}